{"id":580,"date":"2020-02-11T03:29:54","date_gmt":"2020-02-11T03:29:54","guid":{"rendered":"https:\/\/oasis.hostingpruebaspearl.com\/?page_id=580"},"modified":"2026-05-05T17:23:25","modified_gmt":"2026-05-05T23:23:25","slug":"colectores-polvo-humo-neblinas","status":"publish","type":"page","link":"https:\/\/oasis.hostingpruebaspearl.com\/en\/","title":{"rendered":"OASIS &#8211; Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"580\" class=\"elementor elementor-580\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38a8fd27 elementor-section-content-middle elementor-section-height-full elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"38a8fd27\" data-element_type=\"section\" data-e-type=\"section\" id=\"inicio\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-469101b3 elementor-invisible\" data-id=\"469101b3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c6e876e elementor-widget elementor-widget-heading\" data-id=\"3c6e876e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">DISE\u00d1AMOS SOLUCIONES EFICIENTES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-530e36b8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"530e36b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xxl\">Colectores de polvo, humos y neblinas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-649a9d42 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"649a9d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c3424f8 animated-slow elementor-hidden-tablet elementor-hidden-phone ystse elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3c3424f8\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"ystse\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tColectores de polvo humos y neblinas colector industrial dust collectors\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae17cb animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3ae17cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los sistemas industriales <strong>DYNA FLO\u00ae<\/strong>, permiten controlar, capturar y filtrar part\u00edculas suspendidas en el aire de hasta 0.5 micras, evita emisiones contaminantes a la atm\u00f3sfera y mejora la calidad del aire en tus instalaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8545e9 elementor-align-center animated-fast elementor-tablet-align-center elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"b8545e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;flash&quot;,&quot;_animation_delay&quot;:300}\" data-no-translation=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-b8545e9{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd456f1 elementor-align-center animated-fast elementor-tablet-align-center elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"bd456f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;flash&quot;,&quot;_animation_delay&quot;:300}\" data-no-translation=\"\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/productos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Our products<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40a2ac5 elementor-invisible\" data-id=\"40a2ac5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa7a523 elementor-widget elementor-widget-heading\" data-id=\"aa7a523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SOLICITA INFORMACI\u00d3N<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77c1b06 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"77c1b06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b17ba elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"c5b17ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-no-translation=\"\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-element-c5b17ba{display:none !important}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-807608f elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"807608f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-no-translation=\"\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"580\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"807608f\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Grupo Oasis\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCompany\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Company\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_3 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tPhone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_3]\" id=\"form-field-field_3\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Phone\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_5 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCity\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5]\" id=\"form-field-field_5\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"City\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_2 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_2\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tSubject\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_2]\" id=\"form-field-field_2\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Subject\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_1 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_1\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[field_1]\" id=\"form-field-field_1\" rows=\"2\" placeholder=\"Write your message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_4 elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_4\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ld0sP8UAAAAAG92qU_2x9oWv_lzghm1L8W5xU4w\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5b41644]\" id=\"form-field-field_5b41644\" class=\"elementor-field elementor-size-xs \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_aa87804 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_aa87804]\" id=\"form-field-field_aa87804\" class=\"elementor-field elementor-size-xs  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_aa87804\">I have read and accept the <a href=\"https:\/\/oasis.hostingpruebaspearl.com\/privacy-policy\/\" target=\"_blank\" style=\"color:#FFAB00\"> Privacy Policy <\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send Message<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f90cd41 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f90cd41\" data-element_type=\"section\" data-e-type=\"section\" id=\"servicios\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65c23665 animated-slow elementor-invisible\" data-id=\"65c23665\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c324d9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c324d9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f5b6c3f\" data-id=\"2f5b6c3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71c77b7 elementor-widget elementor-widget-heading\" data-id=\"71c77b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">LO QUE TU EMPRESA NECESITA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b66024e animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6b66024e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios Disponibles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2891959 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2891959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1547196e elementor-widget elementor-widget-spacer\" data-id=\"1547196e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71c11797 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"71c11797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f34e991\" data-id=\"7f34e991\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40b2a67 elementor-widget elementor-widget-image\" data-id=\"40b2a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/08\/2ico05-oly640hetzm6zszkwb0otsmt4b8q3j8b1rj5w1p8pw_df54257d0aa5abc3b678ab255aee180b-min.png\" title=\"icono colector\" alt=\"icono colector industrial dust collectors\" class=\"elementor-animation-float\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e83e972 elementor-widget elementor-widget-heading\" data-id=\"4e83e972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fabricaci\u00f3n de Colectores de Polvo,\n\nHumos y Neblinas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f366d3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"73f366d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-288e8b5f elementor-widget elementor-widget-text-editor\" data-id=\"288e8b5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contamos con personal altamente capacitado en producci\u00f3n para la fabricaci\u00f3n de nuestros colectores de polvos, cumpliendo est\u00e1ndares de calidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-36b30f4e\" data-id=\"36b30f4e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c133ff elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7c133ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-float\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tools\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee005fc elementor-widget elementor-widget-heading\" data-id=\"7ee005fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ingenier\u00eda y<br \/>Tecnolog\u00eda<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d90a1a7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6d90a1a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1ae23b elementor-widget elementor-widget-text-editor\" data-id=\"4c1ae23b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El departamento de Ingenier\u00eda, tiene el conocimiento y experiencia para el dise\u00f1o del sistema de extracci\u00f3n m\u00e1s adecuado a su requerimiento.<br \/><br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-32c2784f\" data-id=\"32c2784f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f49c3b6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f49c3b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-float\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-wrench\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfad04a elementor-widget elementor-widget-heading\" data-id=\"cfad04a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicio de<br \/>instalaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29ff33b4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"29ff33b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d33010 elementor-widget elementor-widget-text-editor\" data-id=\"44d33010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El personal encargado de instalaciones, est\u00e1 capacitado para cumplir los m\u00e1s altos est\u00e1ndares de seguridad.<br \/><br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f22cc50 elementor-widget elementor-widget-spacer\" data-id=\"5f22cc50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638fefcb elementor-widget elementor-widget-spacer\" data-id=\"638fefcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eb2192b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eb2192b\" data-element_type=\"section\" data-e-type=\"section\" id=\"proyectos\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5be8f708\" data-id=\"5be8f708\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e943614 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e943614\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6bb82199 animated-slow elementor-invisible\" data-id=\"6bb82199\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4289076d elementor-widget elementor-widget-heading\" data-id=\"4289076d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Galer\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b1dcfb animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"54b1dcfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Proyectos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d067519 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d067519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff9962e elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ff9962e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/SELLO-1-150x150.png\" class=\"elementor-animation-grow-rotate attachment-thumbnail size-thumbnail wp-image-749\" alt=\"grupo oasis 30 a\u00f1os de experiencia sello dust collector\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/SELLO-1-150x150.png 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/SELLO-1-300x297.png 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaed404 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"eaed404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-580 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas contacto dust collectors\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2MiwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMi5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas contacto dust collectors\" aria-describedby=\"gallery-1-3262\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria2.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3262'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas industriales\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2MywidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMy5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas industriales\" aria-describedby=\"gallery-1-3263\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria3.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3263'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores industriales de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2NCwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhNC5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas\" aria-describedby=\"gallery-1-3264\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria4.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3264'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores industriales de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2NSwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhNS5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas\" aria-describedby=\"gallery-1-3265\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria5.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3265'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas dust collectors\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2NiwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhNi5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3266\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria6.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3266'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"dust collectors colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2NywidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhNy5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"dust collectors colectores de polvo humo y neblinas\" aria-describedby=\"gallery-1-3267\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria7.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3267'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"dust collectors colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2OCwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhOC5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"dust collectors colectores de polvo humo y neblinas\" aria-describedby=\"gallery-1-3268\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria8.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3268'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores industriales de polvo humo y neblinas contacto\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2OSwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhOS5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas contacto\" aria-describedby=\"gallery-1-3269\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria9.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3269'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI3MCwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTAuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"dust collectors colectores de polvo humo y neblinas\" aria-describedby=\"gallery-1-3270\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria10.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3270'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores industriales de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI3MSwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTEuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas\" aria-describedby=\"gallery-1-3271\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria11.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3271'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas dust collectors\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI1NywidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTMuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3257\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria13.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3257'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI1OCwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTQuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3258\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria14.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3258'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI1OSwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTUuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3259\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria15.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3259'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2MCwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTYuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3260\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria16.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3260'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI2MSwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMS5qcGciLCJzbGlkZXNob3ciOiJlYWVkNDA0In0%3D\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas dust collectors\" aria-describedby=\"gallery-1-3261\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3261'>\n\t\t\t\tcolectores de polvo humo y neblinas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eaed404\" data-elementor-lightbox-title=\"colectores de polvo humo y neblinas industriales\" data-elementor-lightbox-description=\"colectores de polvo humo y neblinas industriales\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzI1NiwidXJsIjoiaHR0cHM6XC9cL29hc2lzLmhvc3RpbmdwcnVlYmFzcGVhcmwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvb2FzaXNnYWxlcmlhMTIuanBnIiwic2xpZGVzaG93IjoiZWFlZDQwNCJ9\" href='https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"colectores industriales de polvo humo y neblinas industriales dust collectors\" aria-describedby=\"gallery-1-3256\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/11\/oasisgaleria12.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-3256'>\n\t\t\t\tcolectores de polvo humo y neblinas industriales\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10cb421 ystse elementor-widget elementor-widget-text-editor\" data-id=\"10cb421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDust Collector \/ Colector de polvo \/ Colector industrial \/ Colector de polvo \/ Colector industrial \/ Dust Collector\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ebf02e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ebf02e\" data-element_type=\"section\" data-e-type=\"section\" id=\"clientes\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62e48ef animated-slow elementor-invisible\" data-id=\"62e48ef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34a8227 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"34a8227\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clientes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05769ea elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"05769ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0688d animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5a0688d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Clientes de las industrias agroalimentaria, cementera, qu\u00edmica, cer\u00e1mica, automotriz, acerera, entre otras m\u00e1s nos respaldan. Estos son algunos de ellos:\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e62af elementor-arrows-position-outside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"26e62af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:26,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de Im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot01-150x150.png\" alt=\"graftech\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot02-150x150.png\" alt=\"crest\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot03-150x150.png\" alt=\"grupo materias primas\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot04-150x150.png\" alt=\"hi-lex\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/08\/logot05-150x150_9c2eea5060909f6f436953f759f6245c-min-150x150.png\" alt=\"deacero\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot06-150x150.png\" alt=\"blackhawk!\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot07-150x150.png\" alt=\"lamosa\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot08-150x150.png\" alt=\"vitro\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/08\/logot09-150x150_87c63244c7816f4f7760661eec9bf44a-min-150x150.png\" alt=\"metalsa\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/02\/logot010-150x150.png\" alt=\"strongwell\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/08\/logot011-150x150_a18f7bc21e2ee7a676013c9fd03706fe-min-150x150.png\" alt=\"dana\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eae99c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eae99c3\" data-element_type=\"section\" data-e-type=\"section\" id=\"con\u00f3cenos\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dc7953 animated-slow elementor-invisible\" data-id=\"6dc7953\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-02191af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02191af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d1b00f9\" data-id=\"d1b00f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-627eefc animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"627eefc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOSOTROS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d261e2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1d261e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1ea4cc elementor-widget elementor-widget-text-editor\" data-id=\"b1ea4cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La versatilidad de nuestros <span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/es.wikipedia.org\/wiki\/Colector_de_polvo\">Colectores de Polvos<\/a><\/span>, Humos y Neblinas marca <strong style=\"font-weight: 800; color: #004b9f;\">DYNA FLO\u00ae<\/strong>, el detalle en el dise\u00f1o y la calidad durante el proceso de fabricaci\u00f3n e instalaci\u00f3n, nos han permitido trabajar en <strong style=\"font-weight: 800;\">todo M\u00e9xico y parte de Estados Unidos.<\/strong><\/p><p>Nuestros clientes de las industrias agroalimentaria, cementera, qu\u00edmica, cer\u00e1mica, automotriz, acerera, entre otras m\u00e1s nos respaldan.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5421d86\" data-id=\"5421d86\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0269872 elementor-widget elementor-widget-image\" data-id=\"0269872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/08\/mappa2-oly6t6lywpt4jgv13vxdw214kt5lw835xslj6dk7zo_353c5c446213fc1cc9b9c455481d1acf-min.png\" title=\"mapa de m\u00e9xico y estados unidos\" alt=\"mapa de m\u00e9xico y estados unidos\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-362de1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"362de1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-723c344 elementor-invisible\" data-id=\"723c344\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa7e65d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"aa7e65d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-float\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users-cog\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f813ba4 elementor-widget elementor-widget-counter\" data-id=\"f813ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Empleados<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"130\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ff06715 elementor-invisible\" data-id=\"ff06715\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5ef2d4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a5ef2d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-float\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-clipboard-check\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-618b667 elementor-widget elementor-widget-counter\" data-id=\"618b667\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Proyectos<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-681d715 elementor-invisible\" data-id=\"681d715\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be4acd6 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"be4acd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-float\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-handshake\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ebc48 elementor-widget elementor-widget-counter\" data-id=\"97ebc48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Clientes<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"500\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcf5d10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcf5d10\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06ddcf7\" data-id=\"06ddcf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd7166e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd7166e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8ac239b\" data-id=\"8ac239b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd4371b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dd4371b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BLOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-178f463 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"178f463\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-caf4e3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"caf4e3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e081ac0\" data-id=\"e081ac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a015746 elementor-widget elementor-widget-shortcode\" data-id=\"a015746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1506\" class=\"elementor elementor-1506\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c994687 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c994687\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d77a0e\" data-id=\"6d77a0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-798a8ae elementor-grid-tablet-3 elementor-posts__hover-none elementor-grid-3 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"798a8ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns_tablet&quot;:&quot;3&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4157 post type-post status-publish format-standard has-post-thumbnail hentry category-colector-de-humos category-colector-de-neblinas category-colector-de-polvos category-colectores-industriales tag-colector-de-humos tag-colector-de-polvos\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/cuanto-tiempo-duran-los-filtros-de-un-colector-de-polvo-industrial\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro-300x300.jpg\" class=\"attachment-medium size-medium wp-image-4315\" alt=\"filtro-colector-de-polvo-saturado\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/duracion-filtro.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/cuanto-tiempo-duran-los-filtros-de-un-colector-de-polvo-industrial\/\" >\n\t\t\t\t\u00bfCu\u00e1nto tiempo duran los filtros de un colector de polvo industrial?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>El tiempo de vida de los filtros nuevos, ya sean tipo bolsas o de cartuchos se puede determinar durante los primeros d\u00edas de operaci\u00f3n. Cualquier tipo de filtro, con excepci\u00f3n de los que cuentan con membrana de tefl\u00f3n, usan la capa de polvo que se acumula sobre la superficie de estos para limpiar el aire sucio.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/cuanto-tiempo-duran-los-filtros-de-un-colector-de-polvo-industrial\/\" aria-label=\"Read more about \u00bfCu\u00e1nto tiempo duran los filtros de un colector de polvo industrial?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26 May, 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4291 post type-post status-publish format-standard has-post-thumbnail hentry category-colector-de-humos category-colector-de-neblinas category-colector-de-polvos category-colectores-industriales tag-colector-de-humos tag-colector-de-polvos\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-son-las-valvulas-rotativas-o-rotatorias\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"240\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/rotatoria-300x240.jpg\" class=\"attachment-medium size-medium wp-image-4299\" alt=\"valvula-rotativa\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/rotatoria-300x240.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/rotatoria-768x614.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/rotatoria-16x12.jpg 16w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/rotatoria.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-son-las-valvulas-rotativas-o-rotatorias\/\" >\n\t\t\t\t\u00bfQu\u00e9 son las v\u00e1lvulas rotativas o rotatorias?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Una v\u00e1lvula rotatoria o v\u00e1lvula rotativa es un equipo que permite dosificar materiales en polvo, esta puede ser utilizada regularmente en silos, en tolvas, en bandas sinf\u00edn, mezcladores, transportes helicoidales, colectores de polvos, entre otros. <\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-son-las-valvulas-rotativas-o-rotatorias\/\" aria-label=\"Read more about \u00bfQu\u00e9 son las v\u00e1lvulas rotativas o rotatorias?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 May, 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4272 post type-post status-publish format-standard has-post-thumbnail hentry category-colector-de-humos category-colector-de-neblinas category-colector-de-polvos category-colectores-industriales tag-colector-de-humos tag-colector-de-polvos\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-es-un-filtro-electrostatico\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico-300x300.jpg\" class=\"attachment-medium size-medium wp-image-4283\" alt=\"\" srcset=\"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico-300x300.jpg 300w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico-150x150.jpg 150w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico-768x768.jpg 768w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico-12x12.jpg 12w, https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2021\/05\/filtro-electroestatico.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-es-un-filtro-electrostatico\/\" >\n\t\t\t\t\u00bfQu\u00e9 es un filtro Electrost\u00e1tico?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Este tipo de filtro permite capturar micro part\u00edculas como las del humo de cigarro, holl\u00edn, aerosoles o bacterias que flotan en el ambiente, dise\u00f1ados para ayudar a mejorar las condiciones ambientales en hospitales, centros comerciales, oficinas, sala de cines, por mencionar algunas, permiten crear una zona de confort y segura.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/que-es-un-filtro-electrostatico\/\" aria-label=\"Read more about \u00bfQu\u00e9 es un filtro Electrost\u00e1tico?\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t25 May, 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DISE\u00d1AMOS SOLUCIONES EFICIENTES Colectores de polvo, humos y neblinas Colectores de polvo humos y neblinas colector industrial dust collectors Los sistemas industriales DYNA FLO\u00ae, permiten controlar, capturar y filtrar part\u00edculas suspendidas en el aire de hasta 0.5 micras, evita emisiones contaminantes a la atm\u00f3sfera y mejora la calidad del aire en tus instalaciones. Ver nuestros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1359,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-580","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Colectores de Polvo Humos y Neblinas en M\u00e9xico y USA<\/title>\n<meta name=\"description\" content=\"Colectores de polvo, humos y neblinas, colectores industriales. Industrial Dust Collectors. Sistemas de ventilaci\u00f3n industrial. Servicio en todo M\u00e9xico y USA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OASIS - Inicio\" \/>\n<meta property=\"og:description\" content=\"Colectores de polvo, humos y neblinas, colectores industriales. Industrial Dust Collectors. Sistemas de ventilaci\u00f3n industrial. Servicio en todo M\u00e9xico y USA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oasis.hostingpruebaspearl.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Oasis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gpooasis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T23:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/03\/grupooasiscolectoresindustriales1920X1080_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\",\"url\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\",\"name\":\"Colectores de Polvo Humos y Neblinas en M\u00e9xico y USA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/grupooasiscolectoresindustriales1920X1080_3.jpg\",\"datePublished\":\"2020-02-11T03:29:54+00:00\",\"dateModified\":\"2026-05-05T23:23:25+00:00\",\"description\":\"Colectores de polvo, humos y neblinas, colectores industriales. Industrial Dust Collectors. Sistemas de ventilaci\u00f3n industrial. Servicio en todo M\u00e9xico y USA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/grupooasiscolectoresindustriales1920X1080_3.jpg\",\"contentUrl\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/grupooasiscolectoresindustriales1920X1080_3.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"colectores de polvo humo y neblinas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OASIS &#8211; Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#website\",\"url\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\",\"name\":\"Grupo Oasis\",\"description\":\"Colectores de Humo y Polvo\",\"publisher\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#organization\",\"name\":\"Grupo OASIS\",\"url\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/oasis.hostingpruebaspearl.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo_alta_oasis_PNG.png\",\"contentUrl\":\"http:\\\/\\\/oasis.hostingpruebaspearl.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo_alta_oasis_PNG.png\",\"width\":3160,\"height\":1116,\"caption\":\"Grupo OASIS\"},\"image\":{\"@id\":\"https:\\\/\\\/oasis.hostingpruebaspearl.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gpooasis\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Smoke and Mist Dust Collectors in Mexico and USA","description":"Dust, smoke and mist collectors, industrial collectors. Industrial Dust Collectors. Industrial ventilation systems. Service throughout Mexico and the USA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oasis.hostingpruebaspearl.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"OASIS - Inicio","og_description":"Colectores de polvo, humos y neblinas, colectores industriales. Industrial Dust Collectors. Sistemas de ventilaci\u00f3n industrial. Servicio en todo M\u00e9xico y USA.","og_url":"https:\/\/oasis.hostingpruebaspearl.com\/en\/","og_site_name":"Grupo Oasis","article_publisher":"https:\/\/www.facebook.com\/gpooasis","article_modified_time":"2026-05-05T23:23:25+00:00","og_image":[{"width":1920,"height":1080,"url":"http:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/03\/grupooasiscolectoresindustriales1920X1080_3.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oasis.hostingpruebaspearl.com\/","url":"https:\/\/oasis.hostingpruebaspearl.com\/","name":"Smoke and Mist Dust Collectors in Mexico and USA","isPartOf":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#primaryimage"},"image":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#primaryimage"},"thumbnailUrl":"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/03\/grupooasiscolectoresindustriales1920X1080_3.jpg","datePublished":"2020-02-11T03:29:54+00:00","dateModified":"2026-05-05T23:23:25+00:00","description":"Dust, smoke and mist collectors, industrial collectors. Industrial Dust Collectors. Industrial ventilation systems. Service throughout Mexico and the USA.","breadcrumb":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oasis.hostingpruebaspearl.com\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oasis.hostingpruebaspearl.com\/#primaryimage","url":"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/03\/grupooasiscolectoresindustriales1920X1080_3.jpg","contentUrl":"https:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/03\/grupooasiscolectoresindustriales1920X1080_3.jpg","width":1920,"height":1080,"caption":"colectores de polvo humo y neblinas"},{"@type":"BreadcrumbList","@id":"https:\/\/oasis.hostingpruebaspearl.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/oasis.hostingpruebaspearl.com\/"},{"@type":"ListItem","position":2,"name":"OASIS &#8211; Inicio"}]},{"@type":"WebSite","@id":"https:\/\/oasis.hostingpruebaspearl.com\/#website","url":"https:\/\/oasis.hostingpruebaspearl.com\/","name":"Grupo Oasis","description":"Colectores de Humo y Polvo","publisher":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oasis.hostingpruebaspearl.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oasis.hostingpruebaspearl.com\/#organization","name":"Grupo OASIS","url":"https:\/\/oasis.hostingpruebaspearl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oasis.hostingpruebaspearl.com\/#\/schema\/logo\/image\/","url":"http:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/01\/logo_alta_oasis_PNG.png","contentUrl":"http:\/\/oasis.hostingpruebaspearl.com\/wp-content\/uploads\/2020\/01\/logo_alta_oasis_PNG.png","width":3160,"height":1116,"caption":"Grupo OASIS"},"image":{"@id":"https:\/\/oasis.hostingpruebaspearl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gpooasis"]}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/pages\/580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/comments?post=580"}],"version-history":[{"count":274,"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/pages\/580\/revisions"}],"predecessor-version":[{"id":4333,"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/pages\/580\/revisions\/4333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/media\/1359"}],"wp:attachment":[{"href":"https:\/\/oasis.hostingpruebaspearl.com\/en\/wp-json\/wp\/v2\/media?parent=580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}